{"id":12142,"date":"2020-09-17T01:35:36","date_gmt":"2020-09-16T23:35:36","guid":{"rendered":"https:\/\/culturesco.com\/?p=12142"},"modified":"2020-10-04T22:28:32","modified_gmt":"2020-10-04T20:28:32","slug":"new-order-the-perfect-kiss-une-histoire","status":"publish","type":"post","link":"https:\/\/culturesco.com\/index.php\/2020\/09\/17\/new-order-the-perfect-kiss-une-histoire\/","title":{"rendered":"New Order \u2013 The Perfect Kiss &#8211; Une Histoire"},"content":{"rendered":"<h2 style=\"text-align: justify;\">The Perfect Kiss (Version Longue) \u2013 Official Video (1985)<\/h2>\n<figure id=\"attachment_12144\" aria-describedby=\"caption-attachment-12144\" style=\"width: 300px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/i0.wp.com\/culturesco.com\/wp-content\/uploads\/2020\/09\/R-106509-1432924931-3519.jpeg.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-12144\" src=\"https:\/\/i0.wp.com\/culturesco.com\/wp-content\/uploads\/2020\/09\/R-106509-1432924931-3519.jpeg.jpg?resize=300%2C300&#038;ssl=1\" alt=\"New Order - The Perfect Kiss - Single Vinyle\" width=\"300\" height=\"300\" srcset=\"https:\/\/i0.wp.com\/culturesco.com\/wp-content\/uploads\/2020\/09\/R-106509-1432924931-3519.jpeg.jpg?w=300&amp;ssl=1 300w, https:\/\/i0.wp.com\/culturesco.com\/wp-content\/uploads\/2020\/09\/R-106509-1432924931-3519.jpeg.jpg?resize=100%2C100&amp;ssl=1 100w, https:\/\/i0.wp.com\/culturesco.com\/wp-content\/uploads\/2020\/09\/R-106509-1432924931-3519.jpeg.jpg?resize=150%2C150&amp;ssl=1 150w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><figcaption id=\"caption-attachment-12144\" class=\"wp-caption-text\">New Order &#8211; The Perfect Kiss &#8211; Single Vinyle<\/figcaption><\/figure>\n<h3 style=\"text-align: justify;\">Les Quatre Mousquetaires\u2026 Du Cin\u00e9ma<\/h3>\n<p style=\"text-align: justify;\">Il existe des instants captivants o\u00f9 il faut parler d\u2019un moment, d\u2019une vision particuli\u00e8re \u00e0 remettre dans le contexte o\u00f9 l&rsquo;on est saisi la premi\u00e8re fois et qu\u2019on adore <strong><em>ad vitam \u00e6ternam<\/em><\/strong>.<\/p>\n<p style=\"text-align: justify;\"><strong><em>The Perfect Kiss<\/em><\/strong> est sans aucun doute le meilleur single fourni par <strong>New Order<\/strong>, quatuor issu du cultissime groupe <a href=\"https:\/\/culturesco.com\/index.php\/2020\/05\/05\/joy-division-sessions-1977-1981-par-pierre-frederic-charpentier\/\" target=\"_blank\" rel=\"noopener noreferrer\">Joy Division<\/a>, avec l\u2019appoint de <strong>Gillian Gilbert<\/strong>, girlfriend \u00e9ternelle de <strong>Stephen Morris<\/strong>, batteur, d\u00e9couvrant la bo\u00eete \u00e0 rythmes, les synth\u00e9s et tout ce qui est possible de cr\u00e9er avec. Pendant ce temps <strong>Bernard Sumner<\/strong> peaufinait son jeu de guitares et surtout sa voix parce qu\u2019il fallait bien remplacer l\u2019indispensable Ian Curtis, tandis que <strong>Peter Hook<\/strong> aiguisait sa basse comme jamais pour qu\u2019elle devienne non pas un instrument qui incite \u00e0 se tr\u00e9mousser mais qui pousse plut\u00f4t \u00e0 mettre en avant la m\u00e9lodie.<\/p>\n<figure id=\"attachment_12145\" aria-describedby=\"caption-attachment-12145\" style=\"width: 300px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/i0.wp.com\/culturesco.com\/wp-content\/uploads\/2020\/09\/R-695569-1156084541.jpeg.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-12145\" src=\"https:\/\/i0.wp.com\/culturesco.com\/wp-content\/uploads\/2020\/09\/R-695569-1156084541.jpeg.jpg?resize=300%2C285&#038;ssl=1\" alt=\"The Perfect Kiss - Maxi Vynile\" width=\"300\" height=\"285\" srcset=\"https:\/\/i0.wp.com\/culturesco.com\/wp-content\/uploads\/2020\/09\/R-695569-1156084541.jpeg.jpg?resize=300%2C285&amp;ssl=1 300w, https:\/\/i0.wp.com\/culturesco.com\/wp-content\/uploads\/2020\/09\/R-695569-1156084541.jpeg.jpg?resize=442%2C420&amp;ssl=1 442w, https:\/\/i0.wp.com\/culturesco.com\/wp-content\/uploads\/2020\/09\/R-695569-1156084541.jpeg.jpg?w=559&amp;ssl=1 559w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><figcaption id=\"caption-attachment-12145\" class=\"wp-caption-text\">The Perfect Kiss &#8211; Maxi Vynile<\/figcaption><\/figure>\n<h3 style=\"text-align: justify;\"><strong>Le Choix<\/strong><\/h3>\n<p style=\"text-align: justify;\">Mais plut\u00f4t que de parler du morceau en lui-m\u00eame, il faut remonter \u00e0 ce qui a renvers\u00e9 l\u2019id\u00e9e m\u00eame du clip (encore a-t-il malheureusement repris toutes ses d\u00e9bilit\u00e9s faussement cin\u00e9matographique \u00e0 coup de flashes exponentielles ou d\u2019onirismes d\u00e9mesur\u00e9s).<\/p>\n<p style=\"text-align: justify;\">Donc la<strong> Factory<\/strong> fait appel \u00e0 l\u2019idole montante du moment \u00e0 la r\u00e9alisation. Nous sommes fin 1984 \u2013 d\u00e9but 1985 et <strong>Jonathan Demme<\/strong> (1944 \u2013 2017) devient lentement la coqueluche d\u2019Hollywood avec son film <em><strong>Dangereuse sous tous rapports<\/strong> <\/em>avec <strong>M\u00e9lanie Griffith<\/strong> et <strong>Jeff Daniels<\/strong> (qui ne sortira qu\u2019en 1987 en France). Par la suite, histoire de donner envie de baver, il mettra en sc\u00e8ne <strong><em>Le Silence des Agneaux<\/em><\/strong> en 1991 et <strong><em>Philadelphia<\/em><\/strong> en 1993. Ca vous classe son homme tout de suite.<\/p>\n<p style=\"text-align: justify;\">Dans tout bon film et clip, il faut un responsable de la photographie et de la lumi\u00e8re\u00a0hors-pair : pas d\u2019h\u00e9sitation, faisons appel \u00e0 l\u2019un des ma\u00eetres de l\u2019illusion et de sa vision du cin\u00e9ma. Il est fran\u00e7ais, a travaill\u00e9 avec les plus grands, notamment sur <strong><em>La Belle Et La B\u00eate<\/em><\/strong> de <strong>Jean Cocteau<\/strong> et <strong><em>La Bataille Du Rail<\/em><\/strong> de <strong>Ren\u00e9 Cl\u00e9ment<\/strong>. Tout cela en\u2026 1946. <strong>Henri Alekan<\/strong> (1909 \u2013 2001), avec qui il faut associer <strong>Louis Cochet<\/strong>, son \u00e9ternel et valeureux second, est pourtant en train de commencer le tournage de l\u2019un des films les plus importants de toute l\u2019histoire du cin\u00e9ma\u00a0: <strong><em>Les Ailes Du D\u00e9sir<\/em><\/strong> de <strong>Wim Wenders<\/strong>. A 75 ans, il n\u2019h\u00e9site pas \u00e0 affronter <strong>New Order<\/strong> et en m\u00eame temps <strong>Nick Cave And The Bad Seeds<\/strong> et <strong>Crime &amp; The City Solution<\/strong>. Respect total. Dans la foul\u00e9e il embarque <strong>Agn\u00e8s Godard<\/strong>, alors d\u00e9butante, cadreuse sur le film.<\/p>\n<h3 style=\"text-align: justify;\"><em>Les Ailes Du D\u00e9sir &#8211; Wim Wenders (Bande-Annonce)<\/em><\/h3>\n<div class=\"youtube-embed\" data-video_id=\"3lb7nS8i7d0\"><iframe loading=\"lazy\" title=\"Les Ailes du D\u00e9sir - bande-annonce\" width=\"696\" height=\"392\" src=\"https:\/\/www.youtube.com\/embed\/3lb7nS8i7d0\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n<h3 style=\"text-align: justify;\"><strong>Le Tournage<\/strong><\/h3>\n<p style=\"text-align: justify;\">Et voil\u00e0 nos quatre mousquetaires qui d\u00e9barquent en studio pour enregistrer live la version longue. Celle-ci dure pr\u00e8s de dix minutes :<strong><em>The Perfect Kiss<\/em><\/strong>. <strong>New Order<\/strong>, m\u00eame apr\u00e8s le succ\u00e8s mondial de <strong><em>Blue Monday<\/em><\/strong>, demeure un groupe tr\u00e8s introspectif et se demande bien \u00e0 quelle sauce il va \u00eatre mang\u00e9. L\u2019ensemble se d\u00e9roule pourtant comme un \u00e9tat de gr\u00e2ce, en tr\u00e8s peu de prises. On leur demande de jouer r\u00e9ellement, sans playback surtout, sans en rajouter. L\u2019\u00e9quipe de tournage s\u2019occupe du reste. Le final se fera au montage. Et c\u2019est de la magie pure. Des gros plans fixes de chaque musicien, concentr\u00e9s, intenses, avec des instants qui virent volontairement ou non \u00e0 l\u2019hommage.<\/p>\n<h3 style=\"text-align: justify;\"><strong>Le Passage De T\u00e9moin<\/strong><\/h3>\n<p style=\"text-align: justify;\">Une premi\u00e8re fois on aper\u00e7oit, \u00e0 c\u00f4t\u00e9 de <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Peter_Hook\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Peter Hook<\/strong><\/a>, un type accoud\u00e9 \u00e0 la porte et derri\u00e8re lui une lumi\u00e8re blanche qui se profile, donnant une apparence fantomatique. La ressemblance avec <strong>Ian Curtis<\/strong> est sid\u00e9rante. Il regarde, opine du chef, semblant accepter cela et s\u2019en r\u00e9jouit. Peu apr\u00e8s, derri\u00e8re <strong>Bernard Sumner<\/strong>, une affiche d\u2019un concert de <strong>Joy Division<\/strong> annon\u00e7ant la tourn\u00e9e de <strong><em>Unknown Pleasures<\/em><\/strong> symbolise l\u2019importance de ce clip. Les couleurs sont claires, l\u00e9g\u00e8res pendant que la musique est profonde, r\u00e9jouissante mais inqui\u00e9tante, enjou\u00e9e mais respectueuse. Le clip parfait et inoubliable des ann\u00e9es quatre-vingts.<\/p>\n<h3 style=\"text-align: justify;\"><em>New Order &#8211; The Perfect Kiss (Version Longue) &#8211; Clip Officiel<\/em><\/h3>\n<div class=\"youtube-embed\" data-video_id=\"x3XW6NLILqo\"><iframe loading=\"lazy\" title=\"New Order - The Perfect Kiss (Official Music Video) [HD Remaster]\" width=\"696\" height=\"392\" src=\"https:\/\/www.youtube.com\/embed\/x3XW6NLILqo\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n<p style=\"text-align: justify;\"><strong>New Order &#8211; The Perfect Kiss, version longue <\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Official Video (avril 1985)<\/strong><\/p>\n<p style=\"text-align: justify;\">Film\u00e9 par <strong>Jonathan Demme<\/strong><\/p>\n<p style=\"text-align: justify;\">Directeur de la photographie\u00a0: <strong>Henri Alekan<\/strong><\/p>\n<p style=\"text-align: justify;\">Responsable\u00a0lumi\u00e8res : <strong>Louis Cochet<\/strong><\/p>\n<p style=\"text-align: justify;\">Cadreuse\u00a0: <strong>Agn\u00e8s Godard<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Patrick B\u00e9nard<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>The Perfect Kiss (Version Longue) \u2013 Official Video (1985) Les Quatre Mousquetaires\u2026 Du Cin\u00e9ma Il existe des instants captivants o\u00f9 il faut parler d\u2019un moment, d\u2019une vision particuli\u00e8re \u00e0 remettre dans le contexte o\u00f9 l&rsquo;on est saisi la premi\u00e8re fois et qu\u2019on adore ad vitam \u00e6ternam. The Perfect Kiss est sans aucun doute le meilleur [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":12144,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"image","meta":{"tdm_status":"","tdm_grid_status":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[30,34,17,33],"tags":[37,67,54,52,14001,58,12104,12188,4171,14000],"class_list":["post-12142","post","type-post","status-publish","format-image","has-post-thumbnail","category-albums-rock","category-anecdotes-rock","category-carotte-rock-cultures","category-histoire-du-rock","tag-album-rock","tag-anecdotes-rock","tag-cinema","tag-groupe-rock-actuel","tag-histoire-du-cinema","tag-histoire-du-rock","tag-hommage","tag-new-wave","tag-pop-culture","tag-video","post_format-post-format-image"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>New Order \u2013 The Perfect Kiss - Une Histoire - Culturesco<\/title>\n<meta name=\"description\" content=\"CulturesCo | New Order, The Perfect Kiss version longue, vid\u00e9o officielle de 1985, l&#039;histoire d&#039;un tournage racont\u00e9 en d\u00e9tails !\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/culturesco.com\/index.php\/2020\/09\/17\/new-order-the-perfect-kiss-une-histoire\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"New Order \u2013 The Perfect Kiss - Une Histoire - Culturesco\" \/>\n<meta property=\"og:description\" content=\"CulturesCo | New Order, The Perfect Kiss version longue, vid\u00e9o officielle de 1985, l&#039;histoire d&#039;un tournage racont\u00e9 en d\u00e9tails !\" \/>\n<meta property=\"og:url\" content=\"https:\/\/culturesco.com\/index.php\/2020\/09\/17\/new-order-the-perfect-kiss-une-histoire\/\" \/>\n<meta property=\"og:site_name\" content=\"Culturesco\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/radioculturesco\" \/>\n<meta property=\"article:published_time\" content=\"2020-09-16T23:35:36+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-10-04T20:28:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/culturesco.com\/wp-content\/uploads\/2020\/09\/R-106509-1432924931-3519.jpeg.jpg?fit=300%2C300&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Patrick Benard\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@AugusteMarshal\" \/>\n<meta name=\"twitter:site\" content=\"@AugusteMarshal\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Patrick Benard\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/culturesco.com\\\/index.php\\\/2020\\\/09\\\/17\\\/new-order-the-perfect-kiss-une-histoire\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/culturesco.com\\\/index.php\\\/2020\\\/09\\\/17\\\/new-order-the-perfect-kiss-une-histoire\\\/\"},\"author\":{\"name\":\"Patrick Benard\",\"@id\":\"https:\\\/\\\/culturesco.com\\\/#\\\/schema\\\/person\\\/c2ddd6724863f3bbd20a8278df0891f3\"},\"headline\":\"New Order \u2013 The Perfect Kiss &#8211; Une Histoire\",\"datePublished\":\"2020-09-16T23:35:36+00:00\",\"dateModified\":\"2020-10-04T20:28:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/culturesco.com\\\/index.php\\\/2020\\\/09\\\/17\\\/new-order-the-perfect-kiss-une-histoire\\\/\"},\"wordCount\":805,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/culturesco.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/culturesco.com\\\/index.php\\\/2020\\\/09\\\/17\\\/new-order-the-perfect-kiss-une-histoire\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/culturesco.com\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/R-106509-1432924931-3519.jpeg.jpg?fit=300%2C300&ssl=1\",\"keywords\":[\"album rock\",\"Anecdotes Rock\",\"cin\u00e9ma\",\"groupe rock actuel\",\"Histoire du cin\u00e9ma\",\"histoire du rock\",\"Hommage\",\"New Wave\",\"Pop culture\",\"Vid\u00e9o\"],\"articleSection\":[\"Albums rock\",\"Anecdotes rock\",\"Carotte Rock Cultures\",\"Histoire du rock\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/culturesco.com\\\/index.php\\\/2020\\\/09\\\/17\\\/new-order-the-perfect-kiss-une-histoire\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/culturesco.com\\\/index.php\\\/2020\\\/09\\\/17\\\/new-order-the-perfect-kiss-une-histoire\\\/\",\"url\":\"https:\\\/\\\/culturesco.com\\\/index.php\\\/2020\\\/09\\\/17\\\/new-order-the-perfect-kiss-une-histoire\\\/\",\"name\":\"New Order \u2013 The Perfect Kiss - Une Histoire - Culturesco\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/culturesco.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/culturesco.com\\\/index.php\\\/2020\\\/09\\\/17\\\/new-order-the-perfect-kiss-une-histoire\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/culturesco.com\\\/index.php\\\/2020\\\/09\\\/17\\\/new-order-the-perfect-kiss-une-histoire\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/culturesco.com\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/R-106509-1432924931-3519.jpeg.jpg?fit=300%2C300&ssl=1\",\"datePublished\":\"2020-09-16T23:35:36+00:00\",\"dateModified\":\"2020-10-04T20:28:32+00:00\",\"description\":\"CulturesCo | New Order, The Perfect Kiss version longue, vid\u00e9o officielle de 1985, l'histoire d'un tournage racont\u00e9 en d\u00e9tails !\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/culturesco.com\\\/index.php\\\/2020\\\/09\\\/17\\\/new-order-the-perfect-kiss-une-histoire\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/culturesco.com\\\/index.php\\\/2020\\\/09\\\/17\\\/new-order-the-perfect-kiss-une-histoire\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/culturesco.com\\\/index.php\\\/2020\\\/09\\\/17\\\/new-order-the-perfect-kiss-une-histoire\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/culturesco.com\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/R-106509-1432924931-3519.jpeg.jpg?fit=300%2C300&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/culturesco.com\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/R-106509-1432924931-3519.jpeg.jpg?fit=300%2C300&ssl=1\",\"width\":300,\"height\":300,\"caption\":\"New Order - The Perfect Kiss - Single Vinyle\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/culturesco.com\\\/index.php\\\/2020\\\/09\\\/17\\\/new-order-the-perfect-kiss-une-histoire\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/culturesco.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"New Order \u2013 The Perfect Kiss &#8211; Une Histoire\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/culturesco.com\\\/#website\",\"url\":\"https:\\\/\\\/culturesco.com\\\/\",\"name\":\"Culturesco\",\"description\":\"Culturesco | Un bon coup de pied dans ta Culture\",\"publisher\":{\"@id\":\"https:\\\/\\\/culturesco.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/culturesco.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/culturesco.com\\\/#organization\",\"name\":\"CULTURESCO\",\"url\":\"https:\\\/\\\/culturesco.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/culturesco.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/culturesco.com\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/culturesco-logo-blanc250p.png?fit=250%2C250&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/culturesco.com\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/culturesco-logo-blanc250p.png?fit=250%2C250&ssl=1\",\"width\":250,\"height\":250,\"caption\":\"CULTURESCO\"},\"image\":{\"@id\":\"https:\\\/\\\/culturesco.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/radioculturesco\",\"https:\\\/\\\/x.com\\\/AugusteMarshal\",\"https:\\\/\\\/www.instagram.com\\\/carotte_rock_culture\\\/\",\"https:\\\/\\\/www.pinterest.fr\\\/augustemarshal\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCiWLGffqWSXlNnfzp6YwwyQ\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/culturesco.com\\\/#\\\/schema\\\/person\\\/c2ddd6724863f3bbd20a8278df0891f3\",\"name\":\"Patrick Benard\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/i0.wp.com\\\/culturesco.com\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/patrick-benard-2.jpg?fit=90%2C96&ssl=1\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/culturesco.com\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/patrick-benard-2.jpg?fit=90%2C96&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/culturesco.com\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/patrick-benard-2.jpg?fit=90%2C96&ssl=1\",\"caption\":\"Patrick Benard\"},\"description\":\"Ecrivain, chroniqueur, animateur radio, cr\u00e9ateur de la revue \u00ab Cin\u00e9manie \u00bb, autour du cin\u00e9ma dit d\u2019art et d\u2019essai, sp\u00e9cialiste du groupe The Cure, archiviste... 2020 : \\\"Le Post Rock\\\" essai sur le post rock de Mogwa\u00ef \u00e0 Godspeed You Black Emperor - Camion Blanc 2014 : \u00ab On the rocks \u2013le rock de 2007 \u00e0 2014 \u00bb chroniques livres et cd rocks, interviews \u2013Editions Vaillant 2010 : \u00ab Dans la T\u00eate de Robert Smith \u00bb, roman fiction autour de l\u2019histoire des Cure et de Robert Smith \u2013 Edilivres 2007 : \u00ab Chroniques Fr\u00e9n\u00e9tiques, une histoire intime du rock \u00bb, roman, prix Technikart. 2001 : \u00ab Les Iles du D\u00e9sert \u00bb, polar autour du rock \u2013 Editions Nykta\",\"url\":\"https:\\\/\\\/culturesco.com\\\/index.php\\\/author\\\/patrick-benard89\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"New Order \u2013 The Perfect Kiss - Une Histoire - Culturesco","description":"CulturesCo | New Order, The Perfect Kiss version longue, vid\u00e9o officielle de 1985, l'histoire d'un tournage racont\u00e9 en d\u00e9tails !","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/culturesco.com\/index.php\/2020\/09\/17\/new-order-the-perfect-kiss-une-histoire\/","og_locale":"fr_FR","og_type":"article","og_title":"New Order \u2013 The Perfect Kiss - Une Histoire - Culturesco","og_description":"CulturesCo | New Order, The Perfect Kiss version longue, vid\u00e9o officielle de 1985, l'histoire d'un tournage racont\u00e9 en d\u00e9tails !","og_url":"https:\/\/culturesco.com\/index.php\/2020\/09\/17\/new-order-the-perfect-kiss-une-histoire\/","og_site_name":"Culturesco","article_publisher":"https:\/\/www.facebook.com\/radioculturesco","article_published_time":"2020-09-16T23:35:36+00:00","article_modified_time":"2020-10-04T20:28:32+00:00","og_image":[{"width":300,"height":300,"url":"https:\/\/i0.wp.com\/culturesco.com\/wp-content\/uploads\/2020\/09\/R-106509-1432924931-3519.jpeg.jpg?fit=300%2C300&ssl=1","type":"image\/jpeg"}],"author":"Patrick Benard","twitter_card":"summary_large_image","twitter_creator":"@AugusteMarshal","twitter_site":"@AugusteMarshal","twitter_misc":{"\u00c9crit par":"Patrick Benard","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/culturesco.com\/index.php\/2020\/09\/17\/new-order-the-perfect-kiss-une-histoire\/#article","isPartOf":{"@id":"https:\/\/culturesco.com\/index.php\/2020\/09\/17\/new-order-the-perfect-kiss-une-histoire\/"},"author":{"name":"Patrick Benard","@id":"https:\/\/culturesco.com\/#\/schema\/person\/c2ddd6724863f3bbd20a8278df0891f3"},"headline":"New Order \u2013 The Perfect Kiss &#8211; Une Histoire","datePublished":"2020-09-16T23:35:36+00:00","dateModified":"2020-10-04T20:28:32+00:00","mainEntityOfPage":{"@id":"https:\/\/culturesco.com\/index.php\/2020\/09\/17\/new-order-the-perfect-kiss-une-histoire\/"},"wordCount":805,"commentCount":0,"publisher":{"@id":"https:\/\/culturesco.com\/#organization"},"image":{"@id":"https:\/\/culturesco.com\/index.php\/2020\/09\/17\/new-order-the-perfect-kiss-une-histoire\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/culturesco.com\/wp-content\/uploads\/2020\/09\/R-106509-1432924931-3519.jpeg.jpg?fit=300%2C300&ssl=1","keywords":["album rock","Anecdotes Rock","cin\u00e9ma","groupe rock actuel","Histoire du cin\u00e9ma","histoire du rock","Hommage","New Wave","Pop culture","Vid\u00e9o"],"articleSection":["Albums rock","Anecdotes rock","Carotte Rock Cultures","Histoire du rock"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/culturesco.com\/index.php\/2020\/09\/17\/new-order-the-perfect-kiss-une-histoire\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/culturesco.com\/index.php\/2020\/09\/17\/new-order-the-perfect-kiss-une-histoire\/","url":"https:\/\/culturesco.com\/index.php\/2020\/09\/17\/new-order-the-perfect-kiss-une-histoire\/","name":"New Order \u2013 The Perfect Kiss - Une Histoire - Culturesco","isPartOf":{"@id":"https:\/\/culturesco.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/culturesco.com\/index.php\/2020\/09\/17\/new-order-the-perfect-kiss-une-histoire\/#primaryimage"},"image":{"@id":"https:\/\/culturesco.com\/index.php\/2020\/09\/17\/new-order-the-perfect-kiss-une-histoire\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/culturesco.com\/wp-content\/uploads\/2020\/09\/R-106509-1432924931-3519.jpeg.jpg?fit=300%2C300&ssl=1","datePublished":"2020-09-16T23:35:36+00:00","dateModified":"2020-10-04T20:28:32+00:00","description":"CulturesCo | New Order, The Perfect Kiss version longue, vid\u00e9o officielle de 1985, l'histoire d'un tournage racont\u00e9 en d\u00e9tails !","breadcrumb":{"@id":"https:\/\/culturesco.com\/index.php\/2020\/09\/17\/new-order-the-perfect-kiss-une-histoire\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/culturesco.com\/index.php\/2020\/09\/17\/new-order-the-perfect-kiss-une-histoire\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/culturesco.com\/index.php\/2020\/09\/17\/new-order-the-perfect-kiss-une-histoire\/#primaryimage","url":"https:\/\/i0.wp.com\/culturesco.com\/wp-content\/uploads\/2020\/09\/R-106509-1432924931-3519.jpeg.jpg?fit=300%2C300&ssl=1","contentUrl":"https:\/\/i0.wp.com\/culturesco.com\/wp-content\/uploads\/2020\/09\/R-106509-1432924931-3519.jpeg.jpg?fit=300%2C300&ssl=1","width":300,"height":300,"caption":"New Order - The Perfect Kiss - Single Vinyle"},{"@type":"BreadcrumbList","@id":"https:\/\/culturesco.com\/index.php\/2020\/09\/17\/new-order-the-perfect-kiss-une-histoire\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/culturesco.com\/"},{"@type":"ListItem","position":2,"name":"New Order \u2013 The Perfect Kiss &#8211; Une Histoire"}]},{"@type":"WebSite","@id":"https:\/\/culturesco.com\/#website","url":"https:\/\/culturesco.com\/","name":"Culturesco","description":"Culturesco | Un bon coup de pied dans ta Culture","publisher":{"@id":"https:\/\/culturesco.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/culturesco.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/culturesco.com\/#organization","name":"CULTURESCO","url":"https:\/\/culturesco.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/culturesco.com\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/culturesco.com\/wp-content\/uploads\/2022\/04\/culturesco-logo-blanc250p.png?fit=250%2C250&ssl=1","contentUrl":"https:\/\/i0.wp.com\/culturesco.com\/wp-content\/uploads\/2022\/04\/culturesco-logo-blanc250p.png?fit=250%2C250&ssl=1","width":250,"height":250,"caption":"CULTURESCO"},"image":{"@id":"https:\/\/culturesco.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/radioculturesco","https:\/\/x.com\/AugusteMarshal","https:\/\/www.instagram.com\/carotte_rock_culture\/","https:\/\/www.pinterest.fr\/augustemarshal\/","https:\/\/www.youtube.com\/channel\/UCiWLGffqWSXlNnfzp6YwwyQ"]},{"@type":"Person","@id":"https:\/\/culturesco.com\/#\/schema\/person\/c2ddd6724863f3bbd20a8278df0891f3","name":"Patrick Benard","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/i0.wp.com\/culturesco.com\/wp-content\/uploads\/2019\/02\/patrick-benard-2.jpg?fit=90%2C96&ssl=1","url":"https:\/\/i0.wp.com\/culturesco.com\/wp-content\/uploads\/2019\/02\/patrick-benard-2.jpg?fit=90%2C96&ssl=1","contentUrl":"https:\/\/i0.wp.com\/culturesco.com\/wp-content\/uploads\/2019\/02\/patrick-benard-2.jpg?fit=90%2C96&ssl=1","caption":"Patrick Benard"},"description":"Ecrivain, chroniqueur, animateur radio, cr\u00e9ateur de la revue \u00ab Cin\u00e9manie \u00bb, autour du cin\u00e9ma dit d\u2019art et d\u2019essai, sp\u00e9cialiste du groupe The Cure, archiviste... 2020 : \"Le Post Rock\" essai sur le post rock de Mogwa\u00ef \u00e0 Godspeed You Black Emperor - Camion Blanc 2014 : \u00ab On the rocks \u2013le rock de 2007 \u00e0 2014 \u00bb chroniques livres et cd rocks, interviews \u2013Editions Vaillant 2010 : \u00ab Dans la T\u00eate de Robert Smith \u00bb, roman fiction autour de l\u2019histoire des Cure et de Robert Smith \u2013 Edilivres 2007 : \u00ab Chroniques Fr\u00e9n\u00e9tiques, une histoire intime du rock \u00bb, roman, prix Technikart. 2001 : \u00ab Les Iles du D\u00e9sert \u00bb, polar autour du rock \u2013 Editions Nykta","url":"https:\/\/culturesco.com\/index.php\/author\/patrick-benard89\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/culturesco.com\/wp-content\/uploads\/2020\/09\/R-106509-1432924931-3519.jpeg.jpg?fit=300%2C300&ssl=1","jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/paz89I-39Q","_links":{"self":[{"href":"https:\/\/culturesco.com\/index.php\/wp-json\/wp\/v2\/posts\/12142","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/culturesco.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/culturesco.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/culturesco.com\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/culturesco.com\/index.php\/wp-json\/wp\/v2\/comments?post=12142"}],"version-history":[{"count":0,"href":"https:\/\/culturesco.com\/index.php\/wp-json\/wp\/v2\/posts\/12142\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/culturesco.com\/index.php\/wp-json\/wp\/v2\/media\/12144"}],"wp:attachment":[{"href":"https:\/\/culturesco.com\/index.php\/wp-json\/wp\/v2\/media?parent=12142"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/culturesco.com\/index.php\/wp-json\/wp\/v2\/categories?post=12142"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/culturesco.com\/index.php\/wp-json\/wp\/v2\/tags?post=12142"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}